{"id":5629,"date":"2017-08-08T10:23:50","date_gmt":"2017-08-08T08:23:50","guid":{"rendered":"http:\/\/wpdemos.themezaa.com\/pofo\/?page_id=5629"},"modified":"2020-12-23T11:39:39","modified_gmt":"2020-12-23T10:39:39","slug":"portfolio","status":"publish","type":"page","link":"https:\/\/www.xevin.eu\/en\/portfolio\/","title":{"rendered":"Portfolio Xevin Investments"},"content":{"rendered":"<section data-vc-full-width=\"true\" data-vc-full-width-init=\"false\" data-vc-stretch-content=\"true\" class=\"vc_row wpb_row vc_row-fluid  vc_custom_1543799306043 position-relative wow fadeIn pofo-stretch-content vc_row-no-padding vc_row-o-content-top vc_row-flex pofo-row-responsive-6a97ca5c53097\"><div class=\"wpb_column vc_column_container  col-xs-mobile-fullwidth text-center pofo-column-responsive-6a97ca5c53106\"><div class=\"vc_column-inner vc_custom_1542838293060\"><div class=\"wpb_wrapper\"><ul id=\"pofo-portfolio-1\" class=\"portfolio-filter-custom nav nav-tabs border-none portfolio-filter-tab-1 font-weight-600 alt-font text-uppercase text-center text-small filter-style-1 pofo_portfolio_filter_custom_1543791904-2-64\"><li class=\"nav active\"><a href=\"#\" data-filter=\"*\" data-id=\"pofo-portfolio-1\" class=\"xs-display-inline light-gray-text-link text-very-small dynamic-font-size\">ALL CATEGORIES<\/a><\/li><li class=\"nav\"><a href=\"#\" data-id=\"pofo-portfolio-1\" data-filter=\".portfolio-filter-35-pofo-portfolio-1\" class=\"xs-display-inline light-gray-text-link text-very-small dynamic-font-size\">Adtech<\/a><\/li><li class=\"nav\"><a href=\"#\" data-id=\"pofo-portfolio-1\" data-filter=\".portfolio-filter-36-pofo-portfolio-1\" class=\"xs-display-inline light-gray-text-link text-very-small dynamic-font-size\">Digital<\/a><\/li><li class=\"nav\"><a href=\"#\" data-id=\"pofo-portfolio-1\" data-filter=\".portfolio-filter-37-pofo-portfolio-1\" class=\"xs-display-inline light-gray-text-link text-very-small dynamic-font-size\">E-Commerce<\/a><\/li><li class=\"nav\"><a href=\"#\" data-id=\"pofo-portfolio-1\" data-filter=\".portfolio-filter-38-pofo-portfolio-1\" class=\"xs-display-inline light-gray-text-link text-very-small dynamic-font-size\">IoT<\/a><\/li><li class=\"nav\"><a href=\"#\" data-id=\"pofo-portfolio-1\" data-filter=\".portfolio-filter-39-pofo-portfolio-1\" class=\"xs-display-inline light-gray-text-link text-very-small dynamic-font-size\">Marketplace<\/a><\/li><li class=\"nav\"><a href=\"#\" data-id=\"pofo-portfolio-1\" data-filter=\".portfolio-filter-40-pofo-portfolio-1\" class=\"xs-display-inline light-gray-text-link text-very-small dynamic-font-size\">SaaS<\/a><\/li><li class=\"nav\"><a href=\"#\" data-id=\"pofo-portfolio-1\" data-filter=\".portfolio-filter-48-pofo-portfolio-1\" class=\"xs-display-inline light-gray-text-link text-very-small dynamic-font-size\">Social Network<\/a><\/li><\/ul><ul id=\"pofo-portfolio-2\" class=\"portfolio-filter-custom nav nav-tabs border-none portfolio-filter-tab-1 font-weight-600 alt-font text-uppercase text-center text-small filter-style-1 pofo_portfolio_filter_custom_1543792048-2-59\"><li class=\"nav active\"><a href=\"#\" data-filter=\"*\" data-id=\"pofo-portfolio-1\" class=\"xs-display-inline light-gray-text-link text-very-small dynamic-font-size\">ALL STATUS<\/a><\/li><li class=\"nav\"><a href=\"#\" data-id=\"pofo-portfolio-1\" data-filter=\".portfolio-filter-43-pofo-portfolio-1\" class=\"xs-display-inline light-gray-text-link text-very-small dynamic-font-size\">Early Stage<\/a><\/li><li class=\"nav\"><a href=\"#\" data-id=\"pofo-portfolio-1\" data-filter=\".portfolio-filter-44-pofo-portfolio-1\" class=\"xs-display-inline light-gray-text-link text-very-small dynamic-font-size\">Exited<\/a><\/li><li class=\"nav\"><a href=\"#\" data-id=\"pofo-portfolio-1\" data-filter=\".portfolio-filter-45-pofo-portfolio-1\" class=\"xs-display-inline light-gray-text-link text-very-small dynamic-font-size\">Growth<\/a><\/li><li class=\"nav\"><a href=\"#\" data-id=\"pofo-portfolio-1\" data-filter=\".portfolio-filter-46-pofo-portfolio-1\" class=\"xs-display-inline light-gray-text-link text-very-small dynamic-font-size\">Accelerator<\/a><\/li><li class=\"nav\"><a href=\"#\" data-id=\"pofo-portfolio-1\" data-filter=\".portfolio-filter-47-pofo-portfolio-1\" class=\"xs-display-inline light-gray-text-link text-very-small dynamic-font-size\">Seed<\/a><\/li><\/ul><\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-has-fill vc_col-sm-12  col-xs-mobile-fullwidth pofo-column-responsive-6a97ca5c535b8\"><div class=\"vc_column-inner vc_custom_1543798572079\"><div class=\"wpb_wrapper\"><ul class=\"portfolio-grid hover-option4 work-4col gutter-medium  portfolio-infinite-scroll-pagination portfolio-style-4 pofo-portfolio-1\" data-uniqueid=\"pofo-portfolio-1\"><li class=\"grid-sizer\"><\/li><li class=\"grid-item portfolio-filter-35-pofo-portfolio-1 portfolio-filter-44-pofo-portfolio-1  wow fadeInUp portfolio-single-post\"><div class=\"pofo-rich-snippet display-none post-21207 portfolio type-portfolio status-publish format-standard has-post-thumbnail hentry portfolio-category-adtech portfolio-category-exited\"><div class=\"pofo-rich-snippet display-none\"><span class=\"entry-title\">8fish<\/span><span class=\"author vcard\"><a class=\"url fn n\" href=https:\/\/www.xevin.eu\/en\/author\/xevin_user\/>xevin_user<\/a><\/span><span class=\"published\">14 January 2019<\/span><time class=\"updated\" datetime=\"2020-12-29T12:51:01+01:00\">29 December 2020<\/time><\/div><\/div><figure><div class=\"portfolio-img bg-extra-dark-gray pofo-portfolio-page-background\"><img src=\"https:\/\/www.xevin.eu\/wp-content\/uploads\/2019\/01\/8fish_logo.jpg\" width=\"800\" height=\"650\" alt=\"\" srcset=\"https:\/\/www.xevin.eu\/wp-content\/uploads\/2019\/01\/8fish_logo.jpg 800w, https:\/\/www.xevin.eu\/wp-content\/uploads\/2019\/01\/8fish_logo-300x244.jpg 300w, https:\/\/www.xevin.eu\/wp-content\/uploads\/2019\/01\/8fish_logo-768x624.jpg 768w, https:\/\/www.xevin.eu\/wp-content\/uploads\/2019\/01\/8fish_logo-81x66.jpg 81w\" sizes=\"(max-width: 800px) 100vw, 800px\"><\/div><figcaption><div class=\"text-center portfolio-hover-main\"><div class=\"vertical-align-middle portfolio-hover-box\"><div class=\"portfolio-hover-content position-relative\"><div class=\"bg-deep-pink margin-25px-bottom separator-line-horrizontal-medium-light3 display-inline-block\"><\/div><span class=\"text-white line-height-normal alt-font margin-5px-bottom display-block font-weight-600 text-uppercase\">8fish<\/span><p class=\"text-medium-gray text-extra-small no-margin-bottom text-uppercase\">Adtech<\/p><p class=\"text-medium-gray text-extra-small no-margin-bottom portfolio-url text-uppercase\"><a href=\"http:\/\/\" target=\"_blank\"><\/a><\/p><\/div><\/div><\/div><\/figcaption><\/figure><\/li><li class=\"grid-item portfolio-filter-35-pofo-portfolio-1 portfolio-filter-44-pofo-portfolio-1  wow fadeInUp portfolio-single-post\" data-wow-delay=\"100ms\"><div class=\"pofo-rich-snippet display-none post-20987 portfolio type-portfolio status-publish format-standard has-post-thumbnail hentry portfolio-category-adtech portfolio-category-exited\"><div class=\"pofo-rich-snippet display-none\"><span class=\"entry-title\">Ad-Vice<\/span><span class=\"author vcard\"><a class=\"url fn n\" href=https:\/\/www.xevin.eu\/en\/author\/xevin_user\/>xevin_user<\/a><\/span><span class=\"published\">28 November 2018<\/span><time class=\"updated\" datetime=\"2020-12-29T12:52:42+01:00\">29 December 2020<\/time><\/div><\/div><figure><div class=\"portfolio-img bg-extra-dark-gray pofo-portfolio-page-background\"><img src=\"https:\/\/www.xevin.eu\/wp-content\/uploads\/2018\/11\/advice_logo.jpg\" width=\"800\" height=\"650\" alt=\"\" srcset=\"https:\/\/www.xevin.eu\/wp-content\/uploads\/2018\/11\/advice_logo.jpg 800w, https:\/\/www.xevin.eu\/wp-content\/uploads\/2018\/11\/advice_logo-300x244.jpg 300w, https:\/\/www.xevin.eu\/wp-content\/uploads\/2018\/11\/advice_logo-768x624.jpg 768w, https:\/\/www.xevin.eu\/wp-content\/uploads\/2018\/11\/advice_logo-81x66.jpg 81w\" sizes=\"(max-width: 800px) 100vw, 800px\"><\/div><figcaption><div class=\"text-center portfolio-hover-main\"><div class=\"vertical-align-middle portfolio-hover-box\"><div class=\"portfolio-hover-content position-relative\"><div class=\"bg-deep-pink margin-25px-bottom separator-line-horrizontal-medium-light3 display-inline-block\"><\/div><span class=\"text-white line-height-normal alt-font margin-5px-bottom display-block font-weight-600 text-uppercase\">Ad-Vice<\/span><p class=\"text-medium-gray text-extra-small no-margin-bottom text-uppercase\">Adtech<\/p><p class=\"text-medium-gray text-extra-small no-margin-bottom portfolio-url text-uppercase\"><a href=\"http:\/\/\" target=\"_blank\"><\/a><\/p><\/div><\/div><\/div><\/figcaption><\/figure><\/li><li class=\"grid-item portfolio-filter-35-pofo-portfolio-1 portfolio-filter-44-pofo-portfolio-1  wow fadeInUp portfolio-single-post\" data-wow-delay=\"200ms\"><div class=\"pofo-rich-snippet display-none post-21164 portfolio type-portfolio status-publish format-standard has-post-thumbnail hentry portfolio-category-adtech portfolio-category-exited\"><div class=\"pofo-rich-snippet display-none\"><span class=\"entry-title\">AdRino<\/span><span class=\"author vcard\"><a class=\"url fn n\" href=https:\/\/www.xevin.eu\/en\/author\/xevin_user\/>xevin_user<\/a><\/span><span class=\"published\">14 January 2019<\/span><time class=\"updated\" datetime=\"2020-12-29T12:52:52+01:00\">29 December 2020<\/time><\/div><\/div><figure><div class=\"portfolio-img bg-extra-dark-gray pofo-portfolio-page-background\"><img src=\"https:\/\/www.xevin.eu\/wp-content\/uploads\/2019\/01\/adrino_logo.jpg\" width=\"800\" height=\"650\" alt=\"\" srcset=\"https:\/\/www.xevin.eu\/wp-content\/uploads\/2019\/01\/adrino_logo.jpg 800w, https:\/\/www.xevin.eu\/wp-content\/uploads\/2019\/01\/adrino_logo-300x244.jpg 300w, https:\/\/www.xevin.eu\/wp-content\/uploads\/2019\/01\/adrino_logo-768x624.jpg 768w, https:\/\/www.xevin.eu\/wp-content\/uploads\/2019\/01\/adrino_logo-81x66.jpg 81w\" sizes=\"(max-width: 800px) 100vw, 800px\"><\/div><figcaption><div class=\"text-center portfolio-hover-main\"><div class=\"vertical-align-middle portfolio-hover-box\"><div class=\"portfolio-hover-content position-relative\"><div class=\"bg-deep-pink margin-25px-bottom separator-line-horrizontal-medium-light3 display-inline-block\"><\/div><span class=\"text-white line-height-normal alt-font margin-5px-bottom display-block font-weight-600 text-uppercase\">AdRino<\/span><p class=\"text-medium-gray text-extra-small no-margin-bottom text-uppercase\">Adtech<\/p><p class=\"text-medium-gray text-extra-small no-margin-bottom portfolio-url text-uppercase\"><a href=\"http:\/\/www.adrino.pl\" target=\"_blank\">www.adrino.pl<\/a><\/p><\/div><\/div><\/div><\/figcaption><\/figure><\/li><li class=\"grid-item portfolio-filter-36-pofo-portfolio-1 portfolio-filter-44-pofo-portfolio-1  wow fadeInUp portfolio-single-post\" data-wow-delay=\"300ms\"><div class=\"pofo-rich-snippet display-none post-21168 portfolio type-portfolio status-publish format-standard has-post-thumbnail hentry portfolio-category-digital portfolio-category-exited\"><div class=\"pofo-rich-snippet display-none\"><span class=\"entry-title\">Autentika<\/span><span class=\"author vcard\"><a class=\"url fn n\" href=https:\/\/www.xevin.eu\/en\/author\/xevin_user\/>xevin_user<\/a><\/span><span class=\"published\">14 January 2019<\/span><time class=\"updated\" datetime=\"2020-12-29T12:53:03+01:00\">29 December 2020<\/time><\/div><\/div><figure><div class=\"portfolio-img bg-extra-dark-gray pofo-portfolio-page-background\"><img src=\"https:\/\/www.xevin.eu\/wp-content\/uploads\/2019\/01\/autentika_logo.jpg\" width=\"800\" height=\"650\" alt=\"\" srcset=\"https:\/\/www.xevin.eu\/wp-content\/uploads\/2019\/01\/autentika_logo.jpg 800w, https:\/\/www.xevin.eu\/wp-content\/uploads\/2019\/01\/autentika_logo-300x244.jpg 300w, https:\/\/www.xevin.eu\/wp-content\/uploads\/2019\/01\/autentika_logo-768x624.jpg 768w, https:\/\/www.xevin.eu\/wp-content\/uploads\/2019\/01\/autentika_logo-81x66.jpg 81w\" sizes=\"(max-width: 800px) 100vw, 800px\"><\/div><figcaption><div class=\"text-center portfolio-hover-main\"><div class=\"vertical-align-middle portfolio-hover-box\"><div class=\"portfolio-hover-content position-relative\"><div class=\"bg-deep-pink margin-25px-bottom separator-line-horrizontal-medium-light3 display-inline-block\"><\/div><span class=\"text-white line-height-normal alt-font margin-5px-bottom display-block font-weight-600 text-uppercase\">Autentika<\/span><p class=\"text-medium-gray text-extra-small no-margin-bottom text-uppercase\">Digital<\/p><p class=\"text-medium-gray text-extra-small no-margin-bottom portfolio-url text-uppercase\"><a href=\"http:\/\/www.autentika.pl\" target=\"_blank\">www.autentika.pl<\/a><\/p><\/div><\/div><\/div><\/figcaption><\/figure><\/li><li class=\"grid-item portfolio-filter-44-pofo-portfolio-1 portfolio-filter-39-pofo-portfolio-1  wow fadeInUp portfolio-single-post\" data-wow-delay=\"400ms\"><div class=\"pofo-rich-snippet display-none post-21172 portfolio type-portfolio status-publish format-standard has-post-thumbnail hentry portfolio-category-exited portfolio-category-marketplace\"><div class=\"pofo-rich-snippet display-none\"><span class=\"entry-title\">B2B Partner<\/span><span class=\"author vcard\"><a class=\"url fn n\" href=https:\/\/www.xevin.eu\/en\/author\/xevin_user\/>xevin_user<\/a><\/span><span class=\"published\">14 January 2019<\/span><time class=\"updated\" datetime=\"2020-12-29T12:56:25+01:00\">29 December 2020<\/time><\/div><\/div><figure><div class=\"portfolio-img bg-extra-dark-gray pofo-portfolio-page-background\"><img src=\"https:\/\/www.xevin.eu\/wp-content\/uploads\/2019\/01\/b2bpartner.jpg\" width=\"800\" height=\"650\" alt=\"\" srcset=\"https:\/\/www.xevin.eu\/wp-content\/uploads\/2019\/01\/b2bpartner.jpg 800w, https:\/\/www.xevin.eu\/wp-content\/uploads\/2019\/01\/b2bpartner-300x244.jpg 300w, https:\/\/www.xevin.eu\/wp-content\/uploads\/2019\/01\/b2bpartner-768x624.jpg 768w, https:\/\/www.xevin.eu\/wp-content\/uploads\/2019\/01\/b2bpartner-81x66.jpg 81w\" sizes=\"(max-width: 800px) 100vw, 800px\"><\/div><figcaption><div class=\"text-center portfolio-hover-main\"><div class=\"vertical-align-middle portfolio-hover-box\"><div class=\"portfolio-hover-content position-relative\"><div class=\"bg-deep-pink margin-25px-bottom separator-line-horrizontal-medium-light3 display-inline-block\"><\/div><span class=\"text-white line-height-normal alt-font margin-5px-bottom display-block font-weight-600 text-uppercase\">B2B Partner<\/span><p class=\"text-medium-gray text-extra-small no-margin-bottom text-uppercase\">Marketplace<\/p><p class=\"text-medium-gray text-extra-small no-margin-bottom portfolio-url text-uppercase\"><a href=\"http:\/\/\" target=\"_blank\"><\/a><\/p><\/div><\/div><\/div><\/figcaption><\/figure><\/li><li class=\"grid-item portfolio-filter-44-pofo-portfolio-1 portfolio-filter-39-pofo-portfolio-1  wow fadeInUp portfolio-single-post\" data-wow-delay=\"500ms\"><div class=\"pofo-rich-snippet display-none post-21175 portfolio type-portfolio status-publish format-standard has-post-thumbnail hentry portfolio-category-exited portfolio-category-marketplace\"><div class=\"pofo-rich-snippet display-none\"><span class=\"entry-title\">Babys Secret<\/span><span class=\"author vcard\"><a class=\"url fn n\" href=https:\/\/www.xevin.eu\/en\/author\/xevin_user\/>xevin_user<\/a><\/span><span class=\"published\">14 January 2019<\/span><time class=\"updated\" datetime=\"2020-12-29T12:56:38+01:00\">29 December 2020<\/time><\/div><\/div><figure><div class=\"portfolio-img bg-extra-dark-gray pofo-portfolio-page-background\"><img src=\"https:\/\/www.xevin.eu\/wp-content\/uploads\/2019\/01\/babys_secret_logo.jpg\" width=\"800\" height=\"650\" alt=\"\" srcset=\"https:\/\/www.xevin.eu\/wp-content\/uploads\/2019\/01\/babys_secret_logo.jpg 800w, https:\/\/www.xevin.eu\/wp-content\/uploads\/2019\/01\/babys_secret_logo-300x244.jpg 300w, https:\/\/www.xevin.eu\/wp-content\/uploads\/2019\/01\/babys_secret_logo-768x624.jpg 768w, https:\/\/www.xevin.eu\/wp-content\/uploads\/2019\/01\/babys_secret_logo-81x66.jpg 81w\" sizes=\"(max-width: 800px) 100vw, 800px\"><\/div><figcaption><div class=\"text-center portfolio-hover-main\"><div class=\"vertical-align-middle portfolio-hover-box\"><div class=\"portfolio-hover-content position-relative\"><div class=\"bg-deep-pink margin-25px-bottom separator-line-horrizontal-medium-light3 display-inline-block\"><\/div><span class=\"text-white line-height-normal alt-font margin-5px-bottom display-block font-weight-600 text-uppercase\">Babys Secret<\/span><p class=\"text-medium-gray text-extra-small no-margin-bottom text-uppercase\">Marketplace<\/p><p class=\"text-medium-gray text-extra-small no-margin-bottom portfolio-url text-uppercase\"><a href=\"http:\/\/\" target=\"_blank\"><\/a><\/p><\/div><\/div><\/div><\/figcaption><\/figure><\/li><li class=\"grid-item portfolio-filter-37-pofo-portfolio-1 portfolio-filter-45-pofo-portfolio-1  wow fadeInUp portfolio-single-post\" data-wow-delay=\"600ms\"><div class=\"pofo-rich-snippet display-none post-21183 portfolio type-portfolio status-publish format-standard has-post-thumbnail hentry portfolio-category-e-commerce portfolio-category-growth\"><div class=\"pofo-rich-snippet display-none\"><span class=\"entry-title\">Bezokularow.pl<\/span><span class=\"author vcard\"><a class=\"url fn n\" href=https:\/\/www.xevin.eu\/en\/author\/xevin_user\/>xevin_user<\/a><\/span><span class=\"published\">14 January 2019<\/span><time class=\"updated\" datetime=\"2020-12-29T12:56:52+01:00\">29 December 2020<\/time><\/div><\/div><figure><div class=\"portfolio-img bg-extra-dark-gray pofo-portfolio-page-background\"><img src=\"https:\/\/www.xevin.eu\/wp-content\/uploads\/2019\/01\/bez_okularow_logo.jpg\" width=\"800\" height=\"650\" alt=\"\" srcset=\"https:\/\/www.xevin.eu\/wp-content\/uploads\/2019\/01\/bez_okularow_logo.jpg 800w, https:\/\/www.xevin.eu\/wp-content\/uploads\/2019\/01\/bez_okularow_logo-300x244.jpg 300w, https:\/\/www.xevin.eu\/wp-content\/uploads\/2019\/01\/bez_okularow_logo-768x624.jpg 768w, https:\/\/www.xevin.eu\/wp-content\/uploads\/2019\/01\/bez_okularow_logo-81x66.jpg 81w\" sizes=\"(max-width: 800px) 100vw, 800px\"><\/div><figcaption><div class=\"text-center portfolio-hover-main\"><div class=\"vertical-align-middle portfolio-hover-box\"><div class=\"portfolio-hover-content position-relative\"><div class=\"bg-deep-pink margin-25px-bottom separator-line-horrizontal-medium-light3 display-inline-block\"><\/div><span class=\"text-white line-height-normal alt-font margin-5px-bottom display-block font-weight-600 text-uppercase\">Bezokularow.pl<\/span><p class=\"text-medium-gray text-extra-small no-margin-bottom text-uppercase\">E-Commerce<\/p><p class=\"text-medium-gray text-extra-small no-margin-bottom portfolio-url text-uppercase\"><a href=\"http:\/\/www.bezokularow.pl\" target=\"_blank\">www.bezokularow.pl<\/a><\/p><\/div><\/div><\/div><\/figcaption><\/figure><\/li><li class=\"grid-item portfolio-filter-40-pofo-portfolio-1 portfolio-filter-47-pofo-portfolio-1  wow fadeInUp portfolio-single-post\" data-wow-delay=\"700ms\"><div class=\"pofo-rich-snippet display-none post-21179 portfolio type-portfolio status-publish format-standard has-post-thumbnail hentry portfolio-category-saas portfolio-category-seed\"><div class=\"pofo-rich-snippet display-none\"><span class=\"entry-title\">Box of Ads<\/span><span class=\"author vcard\"><a class=\"url fn n\" href=https:\/\/www.xevin.eu\/en\/author\/xevin_user\/>xevin_user<\/a><\/span><span class=\"published\">14 January 2019<\/span><time class=\"updated\" datetime=\"2020-12-29T12:57:03+01:00\">29 December 2020<\/time><\/div><\/div><figure><div class=\"portfolio-img bg-extra-dark-gray pofo-portfolio-page-background\"><img src=\"https:\/\/www.xevin.eu\/wp-content\/uploads\/2019\/01\/boxofads_logo.jpg\" width=\"800\" height=\"650\" alt=\"\" srcset=\"https:\/\/www.xevin.eu\/wp-content\/uploads\/2019\/01\/boxofads_logo.jpg 800w, https:\/\/www.xevin.eu\/wp-content\/uploads\/2019\/01\/boxofads_logo-300x244.jpg 300w, https:\/\/www.xevin.eu\/wp-content\/uploads\/2019\/01\/boxofads_logo-768x624.jpg 768w, https:\/\/www.xevin.eu\/wp-content\/uploads\/2019\/01\/boxofads_logo-81x66.jpg 81w\" sizes=\"(max-width: 800px) 100vw, 800px\"><\/div><figcaption><div class=\"text-center portfolio-hover-main\"><div class=\"vertical-align-middle portfolio-hover-box\"><div class=\"portfolio-hover-content position-relative\"><div class=\"bg-deep-pink margin-25px-bottom separator-line-horrizontal-medium-light3 display-inline-block\"><\/div><span class=\"text-white line-height-normal alt-font margin-5px-bottom display-block font-weight-600 text-uppercase\">Box of Ads<\/span><p class=\"text-medium-gray text-extra-small no-margin-bottom text-uppercase\">Saas<\/p><p class=\"text-medium-gray text-extra-small no-margin-bottom portfolio-url text-uppercase\"><a href=\"http:\/\/\" target=\"_blank\"><\/a><\/p><\/div><\/div><\/div><\/figcaption><\/figure><\/li><li class=\"grid-item portfolio-filter-46-pofo-portfolio-1 portfolio-filter-38-pofo-portfolio-1  wow fadeInUp portfolio-single-post\" data-wow-delay=\"800ms\"><div class=\"pofo-rich-snippet display-none post-21187 portfolio type-portfolio status-publish format-standard has-post-thumbnail hentry portfolio-category-accelerator portfolio-category-iot\"><div class=\"pofo-rich-snippet display-none\"><span class=\"entry-title\">Buildit Accelerator LLC<\/span><span class=\"author vcard\"><a class=\"url fn n\" href=https:\/\/www.xevin.eu\/en\/author\/xevin_user\/>xevin_user<\/a><\/span><span class=\"published\">14 January 2019<\/span><time class=\"updated\" datetime=\"2020-12-29T12:57:19+01:00\">29 December 2020<\/time><\/div><\/div><figure><div class=\"portfolio-img bg-extra-dark-gray pofo-portfolio-page-background\"><img src=\"https:\/\/www.xevin.eu\/wp-content\/uploads\/2019\/01\/buildit_logo.jpg\" width=\"800\" height=\"650\" alt=\"\" srcset=\"https:\/\/www.xevin.eu\/wp-content\/uploads\/2019\/01\/buildit_logo.jpg 800w, https:\/\/www.xevin.eu\/wp-content\/uploads\/2019\/01\/buildit_logo-300x244.jpg 300w, https:\/\/www.xevin.eu\/wp-content\/uploads\/2019\/01\/buildit_logo-768x624.jpg 768w, https:\/\/www.xevin.eu\/wp-content\/uploads\/2019\/01\/buildit_logo-81x66.jpg 81w\" sizes=\"(max-width: 800px) 100vw, 800px\"><\/div><figcaption><div class=\"text-center portfolio-hover-main\"><div class=\"vertical-align-middle portfolio-hover-box\"><div class=\"portfolio-hover-content position-relative\"><div class=\"bg-deep-pink margin-25px-bottom separator-line-horrizontal-medium-light3 display-inline-block\"><\/div><span class=\"text-white line-height-normal alt-font margin-5px-bottom display-block font-weight-600 text-uppercase\">Buildit Accelerator LLC<\/span><p class=\"text-medium-gray text-extra-small no-margin-bottom text-uppercase\">IoT<\/p><p class=\"text-medium-gray text-extra-small no-margin-bottom portfolio-url text-uppercase\"><a href=\"http:\/\/\" target=\"_blank\"><\/a><\/p><\/div><\/div><\/div><\/figcaption><\/figure><\/li><li class=\"grid-item portfolio-filter-43-pofo-portfolio-1 portfolio-filter-38-pofo-portfolio-1  wow fadeInUp portfolio-single-post\" data-wow-delay=\"900ms\"><div class=\"pofo-rich-snippet display-none post-21503 portfolio type-portfolio status-publish format-standard has-post-thumbnail hentry portfolio-category-early-stage portfolio-category-iot\"><div class=\"pofo-rich-snippet display-none\"><span class=\"entry-title\">Coffeecloud.co<\/span><span class=\"author vcard\"><a class=\"url fn n\" href=https:\/\/www.xevin.eu\/en\/author\/xevin_user\/>xevin_user<\/a><\/span><span class=\"published\">2 November 2020<\/span><time class=\"updated\" datetime=\"2020-12-29T12:57:35+01:00\">29 December 2020<\/time><\/div><\/div><figure><div class=\"portfolio-img bg-extra-dark-gray pofo-portfolio-page-background\"><img src=\"https:\/\/www.xevin.eu\/wp-content\/uploads\/2020\/11\/coffeecloud.jpg\" width=\"800\" height=\"650\" alt=\"\" srcset=\"https:\/\/www.xevin.eu\/wp-content\/uploads\/2020\/11\/coffeecloud.jpg 800w, https:\/\/www.xevin.eu\/wp-content\/uploads\/2020\/11\/coffeecloud-300x244.jpg 300w, https:\/\/www.xevin.eu\/wp-content\/uploads\/2020\/11\/coffeecloud-768x624.jpg 768w, https:\/\/www.xevin.eu\/wp-content\/uploads\/2020\/11\/coffeecloud-16x12.jpg 16w, https:\/\/www.xevin.eu\/wp-content\/uploads\/2020\/11\/coffeecloud-81x66.jpg 81w\" sizes=\"(max-width: 800px) 100vw, 800px\"><\/div><figcaption><div class=\"text-center portfolio-hover-main\"><div class=\"vertical-align-middle portfolio-hover-box\"><div class=\"portfolio-hover-content position-relative\"><div class=\"bg-deep-pink margin-25px-bottom separator-line-horrizontal-medium-light3 display-inline-block\"><\/div><span class=\"text-white line-height-normal alt-font margin-5px-bottom display-block font-weight-600 text-uppercase\">Coffeecloud.co<\/span><p class=\"text-medium-gray text-extra-small no-margin-bottom text-uppercase\">IOT<\/p><p class=\"text-medium-gray text-extra-small no-margin-bottom portfolio-url text-uppercase\"><a href=\"http:\/\/coffeecloud.co\" target=\"_blank\">coffeecloud.co<\/a><\/p><\/div><\/div><\/div><\/figcaption><\/figure><\/li><li class=\"grid-item portfolio-filter-36-pofo-portfolio-1 portfolio-filter-44-pofo-portfolio-1  wow fadeInUp portfolio-single-post\" data-wow-delay=\"1000ms\"><div class=\"pofo-rich-snippet display-none post-21191 portfolio type-portfolio status-publish format-standard has-post-thumbnail hentry portfolio-category-digital portfolio-category-exited\"><div class=\"pofo-rich-snippet display-none\"><span class=\"entry-title\">Cogision<\/span><span class=\"author vcard\"><a class=\"url fn n\" href=https:\/\/www.xevin.eu\/en\/author\/xevin_user\/>xevin_user<\/a><\/span><span class=\"published\">14 January 2019<\/span><time class=\"updated\" datetime=\"2020-12-29T12:57:53+01:00\">29 December 2020<\/time><\/div><\/div><figure><div class=\"portfolio-img bg-extra-dark-gray pofo-portfolio-page-background\"><img src=\"https:\/\/www.xevin.eu\/wp-content\/uploads\/2019\/01\/cogision_logo.jpg\" width=\"800\" height=\"650\" alt=\"\" srcset=\"https:\/\/www.xevin.eu\/wp-content\/uploads\/2019\/01\/cogision_logo.jpg 800w, https:\/\/www.xevin.eu\/wp-content\/uploads\/2019\/01\/cogision_logo-300x244.jpg 300w, https:\/\/www.xevin.eu\/wp-content\/uploads\/2019\/01\/cogision_logo-768x624.jpg 768w, https:\/\/www.xevin.eu\/wp-content\/uploads\/2019\/01\/cogision_logo-81x66.jpg 81w\" sizes=\"(max-width: 800px) 100vw, 800px\"><\/div><figcaption><div class=\"text-center portfolio-hover-main\"><div class=\"vertical-align-middle portfolio-hover-box\"><div class=\"portfolio-hover-content position-relative\"><div class=\"bg-deep-pink margin-25px-bottom separator-line-horrizontal-medium-light3 display-inline-block\"><\/div><span class=\"text-white line-height-normal alt-font margin-5px-bottom display-block font-weight-600 text-uppercase\">Cogision<\/span><p class=\"text-medium-gray text-extra-small no-margin-bottom text-uppercase\">Digital<\/p><p class=\"text-medium-gray text-extra-small no-margin-bottom portfolio-url text-uppercase\"><a href=\"http:\/\/www.cogision.com\" target=\"_blank\">www.cogision.com<\/a><\/p><\/div><\/div><\/div><\/figcaption><\/figure><\/li><li class=\"grid-item portfolio-filter-35-pofo-portfolio-1 portfolio-filter-45-pofo-portfolio-1  wow fadeInUp portfolio-single-post\" data-wow-delay=\"1100ms\"><div class=\"pofo-rich-snippet display-none post-21195 portfolio type-portfolio status-publish format-standard has-post-thumbnail hentry portfolio-category-adtech portfolio-category-growth\"><div class=\"pofo-rich-snippet display-none\"><span class=\"entry-title\">Cube Group<\/span><span class=\"author vcard\"><a class=\"url fn n\" href=https:\/\/www.xevin.eu\/en\/author\/xevin_user\/>xevin_user<\/a><\/span><span class=\"published\">14 January 2019<\/span><time class=\"updated\" datetime=\"2020-12-29T12:58:02+01:00\">29 December 2020<\/time><\/div><\/div><figure><div class=\"portfolio-img bg-extra-dark-gray pofo-portfolio-page-background\"><img src=\"https:\/\/www.xevin.eu\/wp-content\/uploads\/2019\/01\/cubegroup_logo.jpg\" width=\"800\" height=\"650\" alt=\"cubegroup.pl\" srcset=\"https:\/\/www.xevin.eu\/wp-content\/uploads\/2019\/01\/cubegroup_logo.jpg 800w, https:\/\/www.xevin.eu\/wp-content\/uploads\/2019\/01\/cubegroup_logo-300x244.jpg 300w, https:\/\/www.xevin.eu\/wp-content\/uploads\/2019\/01\/cubegroup_logo-768x624.jpg 768w, https:\/\/www.xevin.eu\/wp-content\/uploads\/2019\/01\/cubegroup_logo-81x66.jpg 81w\" sizes=\"(max-width: 800px) 100vw, 800px\"><\/div><figcaption><div class=\"text-center portfolio-hover-main\"><div class=\"vertical-align-middle portfolio-hover-box\"><div class=\"portfolio-hover-content position-relative\"><div class=\"bg-deep-pink margin-25px-bottom separator-line-horrizontal-medium-light3 display-inline-block\"><\/div><span class=\"text-white line-height-normal alt-font margin-5px-bottom display-block font-weight-600 text-uppercase\">Cube Group<\/span><p class=\"text-medium-gray text-extra-small no-margin-bottom text-uppercase\">Adtech<\/p><p class=\"text-medium-gray text-extra-small no-margin-bottom portfolio-url text-uppercase\"><a href=\"http:\/\/www.cubegroup.pl\" target=\"_blank\">www.cubegroup.pl<\/a><\/p><\/div><\/div><\/div><\/figcaption><\/figure><\/li><\/ul><div class=\"pagination pofo-portfolio-infinite-scroll display-none\" data-pagination=\"4\"><a href=\"https:\/\/www.xevin.eu\/en\/wp-json\/wp\/v2\/pages\/5629\/page\/2\/\" class=\"alt-font text-small\"><span class=\"old-post\">Older Portfolio<\/span><i class=\"fas fa-long-arrow-alt-right\"><\/i><\/a><\/div><\/div><\/div><\/div><\/section><div class=\"vc_row-full-width vc_clearfix\"><\/div><section data-vc-full-width=\"true\" data-vc-full-width-init=\"false\" class=\"vc_row wpb_row vc_row-fluid   wow fadeIn pofo-stretch-content pofo-stretch-row-container\"><div class=\"wpb_column vc_column_container vc_col-sm-12  col-xs-mobile-fullwidth text-center\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><h2 class=\"text-extra-dark-gray margin-20px-bottom font-weight-600 xh5 display-inline-block alt-font heading-style2  heading-1\" >Jeste\u015bmy dumni z naszych sp\u00f3\u0142ek.<\/h2><h2 class=\"text-extra-dark-gray margin-20px-bottom font-weight-600 xh6 display-inline-block alt-font heading-style2  heading-2\"  style=\"font-weight: 300;\">Inwestujemy w d\u0142u\u017cszym horyzoncie czasowym<br \/>i poszukujemy projekt\u00f3w z podobn\u0105 perspektyw\u0105.<\/h2><\/div><\/div><\/div><\/section><div class=\"vc_row-full-width vc_clearfix\"><\/div>","protected":false},"excerpt":{"rendered":"www.cubegroup.plCube Group SACube Group SA jest specjalistyczn\u0105 agencj\u0105 zajmuj\u0105c\u0105 si\u0119 performance marketingiem ze szczeg\u00f3lnym naciskiem na reklam\u0119 w wyszukiwarkach. Celem Cube Group jest optymalizacja kampanii reklamowych klient\u00f3w pod k\u0105tem ich efektywno\u015bci. W dzia\u0142aniach firma wykorzystuje autorski system do zarz\u0105dzania kampaniami reklamowymi. Kompleksowe us\u0142ugi proponowane przez firm\u0119 obejmuj\u0105 dzia\u0142ania marketingowe SEM, SEO w najpopularniejszych wyszukiwarkach w Polsce. Us\u0142ugi firmy uzupe\u0142nia reklama kontekstowa w sieciach reklamowych oraz realizacja program\u00f3w afiliacyjnych. Kontakt:Andrzej CudnyWWW:www.cubegroup.plKategoria:AdtechStatus:GrowthLokalizacja:Poland","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v16.6.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Portfolio Xevin Investments \u2013 fundusz venture capital w Polsce<\/title>\n<meta name=\"description\" content=\"Portfolio Xevin Investments to projekty zrealizowane przez nas w ostatnim czasie. Zobacz, co mo\u017cemy Ci zaoferowa\u0107.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.xevin.eu\/en\/portfolio\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Portfolio Xevin Investments \u2013 fundusz venture capital w Polsce\" \/>\n<meta property=\"og:description\" content=\"Portfolio Xevin Investments to projekty zrealizowane przez nas w ostatnim czasie. Zobacz, co mo\u017cemy Ci zaoferowa\u0107.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.xevin.eu\/en\/portfolio\/\" \/>\n<meta property=\"og:site_name\" content=\"Xevin Investments - fundusz venture capital\" \/>\n<meta property=\"article:modified_time\" content=\"2020-12-23T10:39:39+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.xevin.eu\/#website\",\"url\":\"https:\/\/www.xevin.eu\/\",\"name\":\"Xevin Investments - fundusz venture capital\",\"description\":\"Jeste\\u015bmy funduszem venture capital specjalizuj\\u0105cym si\\u0119 w nowych mediach, technologiach, Internecie i telekomunikacji.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.xevin.eu\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-GB\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.xevin.eu\/portfolio\/#webpage\",\"url\":\"https:\/\/www.xevin.eu\/portfolio\/\",\"name\":\"Portfolio Xevin Investments \\u2013 fundusz venture capital w Polsce\",\"isPartOf\":{\"@id\":\"https:\/\/www.xevin.eu\/#website\"},\"datePublished\":\"2017-08-08T08:23:50+00:00\",\"dateModified\":\"2020-12-23T10:39:39+00:00\",\"description\":\"Portfolio Xevin Investments to projekty zrealizowane przez nas w ostatnim czasie. Zobacz, co mo\\u017cemy Ci zaoferowa\\u0107.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.xevin.eu\/portfolio\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.xevin.eu\/portfolio\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.xevin.eu\/portfolio\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Strona g\\u0142\\u00f3wna\",\"item\":\"https:\/\/www.xevin.eu\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Portfolio Xevin Investments\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"https:\/\/www.xevin.eu\/en\/wp-json\/wp\/v2\/pages\/5629"}],"collection":[{"href":"https:\/\/www.xevin.eu\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.xevin.eu\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.xevin.eu\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.xevin.eu\/en\/wp-json\/wp\/v2\/comments?post=5629"}],"version-history":[{"count":74,"href":"https:\/\/www.xevin.eu\/en\/wp-json\/wp\/v2\/pages\/5629\/revisions"}],"predecessor-version":[{"id":21628,"href":"https:\/\/www.xevin.eu\/en\/wp-json\/wp\/v2\/pages\/5629\/revisions\/21628"}],"wp:attachment":[{"href":"https:\/\/www.xevin.eu\/en\/wp-json\/wp\/v2\/media?parent=5629"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}